{"id":3046,"date":"2016-09-15T12:30:10","date_gmt":"2016-09-15T12:30:10","guid":{"rendered":"http:\/\/www.helloholidays.ro\/blog\/?p=3046"},"modified":"2019-07-07T13:10:46","modified_gmt":"2019-07-07T10:10:46","slug":"piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun","status":"publish","type":"post","link":"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/","title":{"rendered":"Piata de Craciun de la Munchen &#8211; una dintre cele mai renumite Piete de Craciun"},"content":{"rendered":"<p>Magie, sarbatoare, fericire&#8230;<br \/>\nSunt cateva cuvinte ce ne vin in minte atunci cand ne gandim la Craciun si ne aduc zambetul pe buze, indiferent de starea pe care o avem in acel moment.<\/p>\n<p>Chiar daca este vazut ca o sarbatoare a familiei, petrecuta acasa, marile capitale europene pun la bataie toate ingredientele pentru a-ti oferi un Craciun autentic, de care poti sa te bucuri alaturi de cei dragi.<\/p>\n<p>Tot ce trebuie sa faci este sa iti alegi o destinatie si sa iti pregatesti lista de cumparaturi!<\/p>\n<p>Pe langa piata traditionala din inima Munchenului, in Marienplatz, cea mai vizitata si cea mai cunoscuta deopotriva, cocheta capitala bavareza gazduieste aproximativ 20 de piete de Craciun plus un festival al iernii, cultural-etnic, un sat bavarez de Craciun, patinoare naturale sau artificiale sau piete de Craciun mai speciale, cum ar fi &#8222;Piata Roz&#8221;.<\/p>\n<p>Povestea pietei de Craciun din Munchen incepe &nbsp;inca din secolul al&nbsp;XV-lea, dar documentar este atestata prima data in 1642. In cadrul acestor targuri sau piete de Craciun se pune accent pe produsele traditionale, specifice zonei ce devin emblematice pentru aceasta perioada a anului: turta dulce, renumitii carnati bavarezi (Weisswurst), migdalele prajite si caramelizate, castanele coapte, fructele glazurate, vinul fiert aromat (Gluhwein), jucariile sau decoratiunile din lemn, dar si cristalurile bavareze.<\/p>\n<p>Ce mai&#8230;deja ai toate ingredientele necesare unei vacante pe cinste!<br \/>\nSi nu orice vacanta, ci vacanta de Craciun, prilej de bucurie si momente magice.<br \/>\n&nbsp;<br \/>\nJust take a look!<\/p>\n<hr>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/TA5ojcNG4N0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magie, sarbatoare, fericire&#8230; Sunt cateva cuvinte ce ne vin in minte atunci cand ne gandim la Craciun si ne aduc zambetul pe buze, indiferent de starea pe care o avem in acel moment. Chiar daca este vazut ca o sarbatoare [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1020],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Piata de Craciun de la Munchen - una dintre cele mai renumite Piete de Craciun - Hello Holidays Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piata de Craciun de la Munchen - una dintre cele mai renumite Piete de Craciun - Hello Holidays Blog\" \/>\n<meta property=\"og:description\" content=\"Magie, sarbatoare, fericire&#8230; Sunt cateva cuvinte ce ne vin in minte atunci cand ne gandim la Craciun si ne aduc zambetul pe buze, indiferent de starea pe care o avem in acel moment. Chiar daca este vazut ca o sarbatoare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/\" \/>\n<meta property=\"og:site_name\" content=\"Hello Holidays Blog\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-15T12:30:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-07T10:10:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2016\/09\/60e744aa-9fbd-5c6f-2c21-e66c8c1d638d.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"988\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hello Holidays\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/#website\",\"url\":\"https:\/\/www.helloholidays.ro\/blog\/\",\"name\":\"Hello Holidays Blog\",\"description\":\"Blog de calatorii\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.helloholidays.ro\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#primaryimage\",\"inLanguage\":\"ro-RO\",\"url\":\"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2016\/09\/60e744aa-9fbd-5c6f-2c21-e66c8c1d638d.jpeg\",\"contentUrl\":\"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2016\/09\/60e744aa-9fbd-5c6f-2c21-e66c8c1d638d.jpeg\",\"width\":988,\"height\":598,\"caption\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#webpage\",\"url\":\"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/\",\"name\":\"Piata de Craciun de la Munchen - una dintre cele mai renumite Piete de Craciun - Hello Holidays Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#primaryimage\"},\"datePublished\":\"2016-09-15T12:30:10+00:00\",\"dateModified\":\"2019-07-07T10:10:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/#\/schema\/person\/5bfec4c79ed834c1062b3bde4a23875c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\\u0103\",\"item\":\"https:\/\/www.helloholidays.ro\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piata de Craciun de la Munchen &#8211; una dintre cele mai renumite Piete de Craciun\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/#\/schema\/person\/5bfec4c79ed834c1062b3bde4a23875c\",\"name\":\"Hello Holidays\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.helloholidays.ro\/blog\/#personlogo\",\"inLanguage\":\"ro-RO\",\"url\":\"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2019\/05\/avatar-150x150.png\",\"contentUrl\":\"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2019\/05\/avatar-150x150.png\",\"caption\":\"Hello Holidays\"},\"url\":\"https:\/\/www.helloholidays.ro\/blog\/author\/hello-holidays\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piata de Craciun de la Munchen - una dintre cele mai renumite Piete de Craciun - Hello Holidays Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/","og_locale":"ro_RO","og_type":"article","og_title":"Piata de Craciun de la Munchen - una dintre cele mai renumite Piete de Craciun - Hello Holidays Blog","og_description":"Magie, sarbatoare, fericire&#8230; Sunt cateva cuvinte ce ne vin in minte atunci cand ne gandim la Craciun si ne aduc zambetul pe buze, indiferent de starea pe care o avem in acel moment. Chiar daca este vazut ca o sarbatoare [&hellip;]","og_url":"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/","og_site_name":"Hello Holidays Blog","article_published_time":"2016-09-15T12:30:10+00:00","article_modified_time":"2019-07-07T10:10:46+00:00","og_image":[{"width":988,"height":598,"url":"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2016\/09\/60e744aa-9fbd-5c6f-2c21-e66c8c1d638d.jpeg","path":"\/home\/hello\/public_html\/public\/blog\/wp-content\/uploads\/2016\/09\/60e744aa-9fbd-5c6f-2c21-e66c8c1d638d.jpeg","size":"full","id":3047,"alt":"","pixels":590824,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Hello Holidays","Est. reading time":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.helloholidays.ro\/blog\/#website","url":"https:\/\/www.helloholidays.ro\/blog\/","name":"Hello Holidays Blog","description":"Blog de calatorii","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.helloholidays.ro\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ro-RO"},{"@type":"ImageObject","@id":"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#primaryimage","inLanguage":"ro-RO","url":"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2016\/09\/60e744aa-9fbd-5c6f-2c21-e66c8c1d638d.jpeg","contentUrl":"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2016\/09\/60e744aa-9fbd-5c6f-2c21-e66c8c1d638d.jpeg","width":988,"height":598,"caption":""},{"@type":"WebPage","@id":"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#webpage","url":"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/","name":"Piata de Craciun de la Munchen - una dintre cele mai renumite Piete de Craciun - Hello Holidays Blog","isPartOf":{"@id":"https:\/\/www.helloholidays.ro\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#primaryimage"},"datePublished":"2016-09-15T12:30:10+00:00","dateModified":"2019-07-07T10:10:46+00:00","author":{"@id":"https:\/\/www.helloholidays.ro\/blog\/#\/schema\/person\/5bfec4c79ed834c1062b3bde4a23875c"},"breadcrumb":{"@id":"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.helloholidays.ro\/blog\/piata-de-craciun-de-la-munchen-una-dintre-cele-mai-renumite-piete-de-craciun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/www.helloholidays.ro\/blog\/"},{"@type":"ListItem","position":2,"name":"Piata de Craciun de la Munchen &#8211; una dintre cele mai renumite Piete de Craciun"}]},{"@type":"Person","@id":"https:\/\/www.helloholidays.ro\/blog\/#\/schema\/person\/5bfec4c79ed834c1062b3bde4a23875c","name":"Hello Holidays","image":{"@type":"ImageObject","@id":"https:\/\/www.helloholidays.ro\/blog\/#personlogo","inLanguage":"ro-RO","url":"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2019\/05\/avatar-150x150.png","contentUrl":"https:\/\/www.helloholidays.ro\/blog\/wp-content\/uploads\/2019\/05\/avatar-150x150.png","caption":"Hello Holidays"},"url":"https:\/\/www.helloholidays.ro\/blog\/author\/hello-holidays\/"}]}},"_links":{"self":[{"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/posts\/3046"}],"collection":[{"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/comments?post=3046"}],"version-history":[{"count":1,"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/posts\/3046\/revisions"}],"predecessor-version":[{"id":4917,"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/posts\/3046\/revisions\/4917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/media\/3047"}],"wp:attachment":[{"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/media?parent=3046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/categories?post=3046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.helloholidays.ro\/blog\/wp-json\/wp\/v2\/tags?post=3046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}